{"id":8183,"date":"2024-11-22T13:02:05","date_gmt":"2024-11-22T12:02:05","guid":{"rendered":"https:\/\/itbranschen.com\/?p=8183"},"modified":"2026-07-24T14:50:06","modified_gmt":"2026-07-24T12:50:06","slug":"play-launch-bringt-jede-konferenz-das-ganze-jahr-uber-auf-ihren-bildschirm","status":"publish","type":"post","link":"https:\/\/itbranschen.com\/de\/play-launch-ta-var-konferens-till-din-skarm-hela-aret\/","title":{"rendered":"Play Launch: Bringen Sie unsere Konferenz das ganze Jahr \u00fcber auf Ihren Bildschirm"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wir freuen uns, den Start von WIT Play bekanntzugeben, unserer neuen Plattform, die die Energie der Women in Tech-Konferenzen weiterleben l\u00e4sst! Diese praktische Website (okay, wir nennen sie Plattform) vereint alle inspirierenden Vortr\u00e4ge und Diskussionen der Konferenzen von 2022 bis 2024, sodass Sie jederzeit auf diese wertvollen Inhalte zugreifen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber das ist noch nicht alles! In den kommenden Wochen wird Play auch Inhalte vergangener Konferenzen bis zur\u00fcck ins Jahr 2020 pr\u00e4sentieren. Von wegweisenden Keynotes und lebhaften Podiumsdiskussionen bis hin zu interaktiven Workshops \u2013 Play deckt alles ab. <a class=\"wpil_keyword_link\" href=\"https:\/\/itbranschen.com\/tre-utsedd-till-arets-employer-brand-vinner-guld-i-magnet-awards\/\" title=\"Tre zur Arbeitgebermarke des Jahres gek\u00fcrt \u2013 gewinnt Gold bei den Magnet Awards\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"9475\">KI<\/a> Und <a href=\"https:\/\/itbranschen.com\/category\/cybersakerhet\/\">Cybersicherheit<\/a> f\u00fcr Karriereberatung und Mentoring.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMan kann es sich wie eine besonders leistungsstarke Seite vorstellen, die jahrelang gro\u00dfartige Inhalte sammelt\u201d, sagt er. <a href=\"https:\/\/womenintech.se\/speakers\/asa-johansen\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Asa Johansson<\/a>, unser Direktor. Unser Ziel mit Play ist es, die Inspiration und das Lernen jeden Tag aufrechtzuerhalten, nicht nur w\u00e4hrend der Konferenz. Indem wir diese Erkenntnisse das ganze Jahr \u00fcber zug\u00e4nglich machen, hoffen wir, die Gemeinschaft zu st\u00e4rken und weiter auszubauen. <a class=\"wpil_keyword_link\" href=\"https:\/\/itbranschen.com\/mot-nagra-av-de-kvinnor-som-garmin-firar-pa-internationella-kvinnodagen\/\" title=\"Lernen Sie einige der Frauen kennen, die Garmin am Internationalen Frauentag feiert.\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"2463\">Frauen<\/a> im Technologiebereich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Play ist \u00e4u\u00dferst benutzerfreundlich, sodass Sie ganz einfach Vortr\u00e4ge und Diskussionen finden und genie\u00dfen k\u00f6nnen, die Sie interessieren. Egal, ob Sie die Konferenz verpasst haben oder einfach Ihre Lieblingsvortr\u00e4ge noch einmal erleben m\u00f6chten \u2013 mit Play sind Sie bestens ger\u00fcstet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie \u00c5sa sagt: \u201cBeim Spielen geht es nicht nur darum, Konferenzmomente wieder aufleben zu lassen \u2013 es geht darum, das Gespr\u00e4ch am Laufen zu halten und ein st\u00e4rkeres, besser vernetztes Netzwerk aufzubauen.\u201c <a href=\"https:\/\/itbranschen.com\/the-state-of-women-in-tech-2024\/\" data-type=\"post\" data-id=\"7793\">Frauen in der Technologie<\/a>.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Women in Tech-Konferenz stand schon immer f\u00fcr Empowerment, und mit Play heben wir sie auf die n\u00e4chste Stufe. Freuen Sie sich darauf, in diese inspirierenden Momente einzutauchen und Neues zu entdecken. <a class=\"wpil_keyword_link\" href=\"https:\/\/itbranschen.com\/valkommen-till-den-nya-eran-av-microsoft-teams\/\" title=\"Willkommen in der neuen \u00c4ra von Microsoft Teams\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"9774\">neu<\/a>. <a href=\"https:\/\/womenintech.se\/play\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Play ist eure neue Anlaufstelle f\u00fcr alles rund um Frauen in der Technologiebranche!<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/itbranschen.com\/toca-boca-lanserar-sitt-forsta-multiplayerspel-nagonsin-toca-boca-days\/\"><\/a>Mehr Informationen erhalten Sie bei Play \u2013 Ihrer ganzj\u00e4hrigen Anlaufstelle f\u00fcr technische Inspiration und Weiterbildung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"\u200b\ufeffWIT Play \u00e4r en ny plattform som koncentrerar Women in Tech-konferensernas b\u00e4sta inneh\u00e5ll fr\u00e5n 2020 till 2024, och skapar ett st\u00e4ndigt fl\u00f6de av inspiration och l\u00e4rande f\u00f6r kvinnor inom tech.\ufeff\u200b","protected":false},"author":1,"featured_media":8187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[249],"tags":[3069,1589,3071,308,3075,8,3073,250],"itb_content_type":[],"class_list":["post-8183","post","type-post","status-publish","format-standard","has-post-thumbnail","category-women-in-tech","tag-it-sakerhet-nyheter-sverige","tag-it-kanalen","tag-nordisk-it-media","tag-play-launch","tag-svensk-it-nyhetssajt","tag-sverige","tag-tech-tidningen","tag-women-in-tech","cs-entry","cs-video-wrap"],"_links":{"self":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/posts\/8183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/comments?post=8183"}],"version-history":[{"count":0,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/posts\/8183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/media\/8187"}],"wp:attachment":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/media?parent=8183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/categories?post=8183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/tags?post=8183"},{"taxonomy":"itb_content_type","embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/itb_content_type?post=8183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}