{"id":29285,"date":"2026-07-21T08:45:55","date_gmt":"2026-07-21T06:45:55","guid":{"rendered":"https:\/\/itbranschen.com\/?p=29285"},"modified":"2026-07-24T14:53:54","modified_gmt":"2026-07-24T12:53:54","slug":"connectwise-ki-plattform-predictive-it-msp","status":"publish","type":"post","link":"https:\/\/itbranschen.com\/de\/connectwise-ai-plattform-prediktiv-it-msp\/","title":{"rendered":"ConnectWise bringt eine neue KI-Plattform auf den Markt, die Managed Service Providern (MSPs) beim \u00dcbergang von reaktivem Support zu vorausschauender IT helfen soll."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>ConnectWise stellt seine neue KI-gest\u00fctzte Plattform ab sofort allgemein zur Verf\u00fcgung. Die Plattform vereint PSA, RMM, Cybersicherheit, Fernzugriff, Automatisierung, KI-Agenten und Integrationen in einem gemeinsamen \u00d6kosystem, um Managed Service Provider (MSPs) und IT-Teams ein proaktiveres, effizienteres und datengetriebenes Arbeiten zu erm\u00f6glichen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ConnectWise, ein f\u00fchrender Anbieter von Software und Dienstleistungen f\u00fcr IT-L\u00f6sungsanbieter, gibt bekannt, dass <strong><a href=\"https:\/\/www.connectwise.com\/platform\" target=\"_blank\" data-schema-attribute=\"mentions\" rel=\"noreferrer noopener\">ConnectWise-Plattform<\/a><\/strong> Die Plattform steht ab sofort allen Kunden zur Verf\u00fcgung. Laut Unternehmen handelt es sich um die branchenweit erste speziell f\u00fcr Managed Service Provider entwickelte Plattform, die den \u00dcbergang von reaktiven IT-Abl\u00e4ufen zu einem vorausschauenden und KI-gest\u00fctzten Gesch\u00e4ftsmodell erm\u00f6glicht.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" title=\"Hero Homepage Nobg | Die IT-Branche\" src=\"https:\/\/www.connectwise.com\/contentassets\/a6a1774a4e144b4a8ea8e89845e5b5c9\/hero-image_homepage_nobg.svg\" alt=\"Die ConnectWise-Plattform vereint KI, Automatisierung, Cybersicherheit und MSP-Tools in einer gemeinsamen Plattform f\u00fcr intelligente und vorausschauende IT-Operationen.\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Plattform bietet Managed Service Providern (MSPs) und internen IT-Abteilungen eine gemeinsame, KI-integrierte Betriebsumgebung, die die im t\u00e4glichen Servicebetrieb eingesetzten Systeme miteinander verbindet. Die L\u00f6sung umfasst ConnectWise PSA, ConnectWise RMM, ScreenConnect, ConnectWise SIEM, Automatisierung, Orchestrierung, ConnectWise AI Agents, Dokumentation, Abrechnung, Datensicherung sowie Integrationen mit einem offenen \u00d6kosystem von Drittanbieterl\u00f6sungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr <a href=\"https:\/\/itbranschen.com\/tag\/connectwise\/\" data-type=\"post_tag\" data-id=\"5901\">ConnectWise<\/a> F\u00fcr Kunden bedeutet dies, dass KI nicht als separates Werkzeug neben dem Unternehmen fungiert. Stattdessen ist KI direkt in Arbeitsabl\u00e4ufe, Daten und den Gesch\u00e4ftskontext integriert, was laut Unternehmen dazu beitr\u00e4gt, die Erstellung, Priorisierung, Bearbeitung, Dokumentation, Rechnungsstellung und Nachverfolgung von Servicef\u00e4llen zu optimieren.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" title=\"Plattform-Webseite und Pr\u00e4sentationen mit abgerundeten Ecken | Die IT-Branche\" src=\"https:\/\/www.connectwise.com\/contentassets\/6537ccf3f5e94edd85172b3aba109c6a\/platform-webpage-and-presentations---rounded-corners-2.png\" alt=\"Die ConnectWise-Plattform vereint KI, Automatisierung, Cybersicherheit und MSP-Tools in einer gemeinsamen Plattform f\u00fcr intelligente und vorausschauende IT-Operationen.\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">KI ist dort integriert, wo gearbeitet wird.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.connectwise.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">ConnectWise<\/a><\/strong> KI-Agenten sind so konzipiert, dass sie direkt in die bestehenden Arbeitsabl\u00e4ufe der Serviceorganisation integriert werden k\u00f6nnen. Sie helfen bei der Interpretation eingehender F\u00e4lle, unterst\u00fctzen die Triage und Priorisierung, verbessern die Dokumentation, koordinieren die Automatisierung und schaffen eine einheitlichere Arbeitsweise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Starport <a href=\"https:\/\/itbranschen.com\/category\/it-tjanster\/\">Managed Services<\/a> ist eines der Unternehmen, die die L\u00f6sung bereits einsetzen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cConnectWise AI Agents hat uns geholfen, von Experimenten mit KI zu messbaren operativen Ergebnissen \u00fcberzugehen. Durch die Integration von KI in unsere Arbeitsabl\u00e4ufe f\u00fcr Triage, Bewertung und technischen Support haben wir die Qualit\u00e4t verbessert, den manuellen Aufwand reduziert und Kapazit\u00e4ten im Service Desk freigesetzt.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/aboeker\/\" target=\"_blank\" data-schema-attribute=\"mentions\" rel=\"noreferrer noopener sponsored\">Aaron Boeker<\/a>, Chief Service Officer, Starport <a href=\"https:\/\/itbranschen.com\/category\/it-tjanster\/\">Managed Services<\/a><\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Nach der Implementierung von ConnectWise AI Agents berichtet Starport \u00fcber folgende Ergebnisse:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>25 Prozent k\u00fcrzere durchschnittliche Bearbeitungszeit pro Fall<\/li>\n\n\n\n<li>28 Prozent weniger Eskalationen<\/li>\n\n\n\n<li>40 Prozent k\u00fcrzere durchschnittliche Aufl\u00f6sungszeit<\/li>\n\n\n\n<li>20 Prozent mehr gel\u00f6ste F\u00e4lle pro Tag<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Laut ConnectWise zeigen die Ergebnisse, wie KI zu einer effizienteren Leistungserbringung beitragen kann, w\u00e4hrend Unternehmen schrittweise die Datenqualit\u00e4t, Automatisierung und Konsistenz aufbauen, die erforderlich sind, um Muster zu erkennen, Probleme vorherzusehen und wiederkehrende Vorf\u00e4lle im Laufe der Zeit zu reduzieren.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"ConnectWise: Die Zukunft der pr\u00e4diktiven IT\u2122\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/bNT7w77EIGc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Von einzelnen Werkzeugen bis hin zu einer zusammenh\u00e4ngenden Plattform<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">ConnectWise beschreibt die Einf\u00fchrung als einen Wandel von separaten IT-Tools hin zu einer zusammenh\u00e4ngenden Plattform, auf der gemeinsam genutzte Daten, integrierte Arbeitsabl\u00e4ufe, eingebaute KI-Agenten, Automatisierung, Orchestrierung und offene Integrationen zusammenarbeiten, um einen intelligenteren und proaktiveren IT-Betrieb zu schaffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Entwicklung findet zeitgleich mit dem Markt f\u00fcr beides statt. <a href=\"https:\/\/itbranschen.com\/category\/it-tjanster\/\">Managed Services<\/a> Und die k\u00fcnstliche Intelligenz entwickelt sich weiterhin rasant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut dem Analyseunternehmen <strong>MarketsandMarkets<\/strong> Der globale Markt f\u00fcr Managed Services wird voraussichtlich wachsen von <strong>460,59 Milliarden US-Dollar im Jahr 2026<\/strong> Zu <strong>705,22 Milliarden US-Dollar im Jahr 2031<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gleichzeitig beurteilen <strong>Fortune Business Insights<\/strong> dass der globale KI-Markt wachsen wird von <strong>375,93 Milliarden US-Dollar im Jahr 2026<\/strong> Zu <strong>2,48 Billionen US-Dollar im Jahr 2034<\/strong>, entsprechend einem durchschnittlichen j\u00e4hrlichen Wachstum von <strong>26,6 Prozent<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut ConnectWise bedeutet diese Entwicklung, dass MSPs Plattformen ben\u00f6tigen, auf denen KI ein integrierter Bestandteil des Gesch\u00e4fts wird und nicht nur ein eigenst\u00e4ndiges Werkzeug darstellt.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cDer Wert von ConnectWise AI Agents liegt darin, dass die KI direkt in die Plattform integriert ist, auf der unser Team bereits arbeitet. Im PSA-System erhalten wir eine kontrolliertere M\u00f6glichkeit, KI einzusetzen, basierend auf Fallhistorie, Kundenkontext und Daten aus unseren Serviceprozessen, anstatt uns auf eigenst\u00e4ndige KI-Tools zu verlassen.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/jason-haveman-614392143\/\" target=\"_blank\" data-schema-attribute=\"mentions\" rel=\"noreferrer noopener sponsored\">Jason Haveman<\/a>, COO, InsITe Business Solutions<\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Der n\u00e4chste Schritt ist eine verst\u00e4rkte Automatisierung und KI-gest\u00fctzte Arbeitsabl\u00e4ufe.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">ConnectWise k\u00fcndigt an, die Plattform kontinuierlich mit mehr KI-Funktionen, intelligenter Workflow-Orchestrierung, autonomen KI-Agenten und erweiterten Integrationen weiterzuentwickeln, mit dem Ziel, Partner schrittweise von reaktivem Support zu autonomeren und vorausschauenden IT-Operationen zu f\u00fchren.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cDas traditionelle MSP-Modell hat ausgedient. Die ConnectWise-Plattform bietet der Branche ein neues Gesch\u00e4ftsmodell, in dem fragmentierte Tools durch vernetzte Intelligenz, automatisierte Ausf\u00fchrung und messbaren Gesch\u00e4ftswert ersetzt werden. Die Plattform wurde entwickelt, um unsere Partner dabei zu unterst\u00fctzen, Komplexit\u00e4t zu reduzieren, schneller zu handeln und bessere Ergebnisse f\u00fcr ihre Kunden zu erzielen, w\u00e4hrend wir in das Zeitalter der pr\u00e4diktiven IT eintreten.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/mannyrivelo\/\" target=\"_blank\" data-schema-attribute=\"mentions\" rel=\"noreferrer noopener sponsored\">Manny Rivelo<\/a>, CEO, ConnectWise<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Unternehmen, die mehr \u00fcber die ConnectWise-Plattform erfahren m\u00f6chten, k\u00f6nnen \u00fcber die ConnectWise-Website eine Demo buchen, den potenziellen ROI f\u00fcr ihre Service-Desk-Abl\u00e4ufe berechnen oder ihre Bereitschaft f\u00fcr pr\u00e4diktive IT bewerten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcber ConnectWise<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">ConnectWise wird von mehr als <strong>100.000 IT-Dienstleister weltweit<\/strong> Das Unternehmen vereint PSA, RMM, Cybersicherheit und Datenschutz auf einer einzigen Plattform, in die KI und pr\u00e4diktive Analysen durchg\u00e4ngig integriert sind. Dank intelligenter Automatisierung und eines offenen Integrations-\u00d6kosystems unterst\u00fctzt das Unternehmen IT-Anbieter dabei, proaktiver zu arbeiten, Komplexit\u00e4t zu reduzieren und ihren Kunden sicherere und effizientere Services zu bieten. Mit \u00fcber 40 Jahren Erfahrung konzentriert sich das Unternehmen auf <strong>ConnectWise<\/strong> bei der Unterst\u00fctzung seiner Partner bei der Weiterentwicklung ihrer Gesch\u00e4fte durch effizientere Abl\u00e4ufe, verbesserte Serviceleistungen und skalierbare Gesch\u00e4ftsmodelle.<\/p>","protected":false},"excerpt":{"rendered":"\u200b\ufeffConnectWise nya plattform samlar AI, automatisering och cybers\u00e4kerhet i en integrerad l\u00f6sning som hj\u00e4lper MSP att g\u00e5 fr\u00e5n reaktiv support till intelligent och prediktiv IT-hantering.\ufeff\u200b","protected":false},"author":1,"featured_media":29288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":["large-header","archive"],"csco_post_video_location_hash":"ex523yu27qomruagxa7","csco_post_video_url":"https:\/\/www.youtube.com\/watch?v=bNT7w77EIGc","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[47],"tags":[24,1266,1422,1553,286,5901,7845,7847,7846,7850,31,1094,2426,189,1720,2349,7849,1550,215,2751,2476,2145,908,7851,2344,5902,4899,51,7848,7378],"itb_content_type":[],"class_list":["post-29285","post","type-post","status-publish","format-standard","has-post-thumbnail","category-artificiell-intelligens","tag-ai","tag-ai-agenter","tag-artificiell-intelligens","tag-automatisering","tag-cloud","tag-connectwise","tag-connectwise-ai","tag-connectwise-ai-agents","tag-connectwise-platform","tag-connectwise-siem","tag-cybersakerhet","tag-digital-transformation","tag-enterprise-ai","tag-generativ-ai","tag-it-management","tag-it-operations","tag-it-automation-2","tag-it-drift","tag-it-infrastruktur","tag-itsm","tag-managed-service-provider","tag-managed-services","tag-msp","tag-orkestrering","tag-prediktiv-it","tag-psa","tag-rmm","tag-saas","tag-screenconnect","tag-servicedesk","cs-entry","cs-video-wrap"],"_links":{"self":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/posts\/29285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/comments?post=29285"}],"version-history":[{"count":0,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/posts\/29285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/media\/29288"}],"wp:attachment":[{"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/media?parent=29285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/categories?post=29285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/tags?post=29285"},{"taxonomy":"itb_content_type","embeddable":true,"href":"https:\/\/itbranschen.com\/de\/wp-json\/wp\/v2\/itb_content_type?post=29285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}